{"id":26569,"date":"2022-06-12T16:49:17","date_gmt":"2022-06-12T14:49:17","guid":{"rendered":"https:\/\/www.camaeleon.org\/?p=26569"},"modified":"2022-07-01T22:55:26","modified_gmt":"2022-07-01T20:55:26","slug":"video-interview-mit-uwe-conradt-zu-deutsch-franzoesischen-beziehungen-schul-digitalisierung-und-radverkehr-in-saarbruecken","status":"publish","type":"post","link":"https:\/\/www.camaeleon.org\/en\/2022\/06\/12\/video-interview-mit-uwe-conradt-zu-deutsch-franzoesischen-beziehungen-schul-digitalisierung-und-radverkehr-in-saarbruecken\/","title":{"rendered":"Video-Interview mit Uwe Conradt zu deutsch-franz\u00f6sischen Beziehungen, Schul-Digitalisierung und Radverkehr in Saarbr\u00fccken"},"content":{"rendered":"<p>Hoher Besuch am DFG! Der Oberb\u00fcrgermeister von Saarbr\u00fccken, Uwe Conradt, hat unserer Schule am 23. Mai einen Besuch abgestattet, um diese besser kennen zu lernen und einen Einblick in das Leben der Sch\u00fcler:innen hier zu bekommen. Nachdem wir ihm eine kleine Tour durch das Geb\u00e4ude gegeben haben, haben wir ihm ein paar Fragen zu seinen Projekten und Pl\u00e4nen f\u00fcr Saarbr\u00fccken und \u00fcber seine Partei, die CDU gestellt. Das Video dazu k\u00f6nnt ihr hier sehen:<\/p>\n<div class=\"lyte-wrapper\" style=\"width:1280px;max-width:100%;margin:5px auto;\"><div class=\"lyMe hidef\" id=\"WYL_MRtvbfrTqFE\"><div id=\"lyte_MRtvbfrTqFE\" data-src=\"https:\/\/www.camaeleon.org\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FMRtvbfrTqFE%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/MRtvbfrTqFE\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.camaeleon.org\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FMRtvbfrTqFE%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"1280\" height=\"700\" \/><br \/>Watch this video on YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:1280px;margin:5px auto;\"><br\/><span class=\"lyte_disclaimer\">By clicking on the video, you establish a connection to Youtube servers. More information in the <a href=\"https:\/\/www.camaeleon.org\/en\/mentions-legales\/declaration-de-protection-des-donnees\/\">privacy statement<\/a>.<\/span><\/div><\/p>\n<p><br \/>\n<br \/>\n<br \/>\n<br \/>\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoher Besuch am DFG! Der Oberb\u00fcrgermeister von Saarbr\u00fccken, Uwe Conradt, hat unserer Schule am 23. Mai einen Besuch abgestattet, um diese besser kennen zu lernen<\/p>\n","protected":false},"author":143,"featured_media":26609,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[10,662],"tags":[957,876,1110,2022,2023,302,2021],"coauthors":[1208,744,1782,1788,1209],"class_list":["post-26569","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politique","category-sarrebruck","tag-deutsch-franzoesische-beziehungen","tag-deutsch-franzoesische-freundschaft","tag-digitalisierung","tag-oberbuergermeister","tag-radfahren","tag-saarbruecken","tag-uwe-conradt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Video-Interview mit Uwe Conradt zu deutsch-franz\u00f6sischen Beziehungen, Schul-Digitalisierung und Radverkehr in Saarbr\u00fccken - Cam\u00e4l\u00e9on<\/title>\n<meta name=\"description\" content=\"Der Oberb\u00fcrgermeister von Saarbr\u00fccken, Uwe Conradt, hat unserer Schule am 23. Mai einen Besuch abgestattet, um diese besser kennen zu lernen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.camaeleon.org\/en\/2022\/06\/12\/video-interview-mit-uwe-conradt-zu-deutsch-franzoesischen-beziehungen-schul-digitalisierung-und-radverkehr-in-saarbruecken\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Video-Interview mit Uwe Conradt zu deutsch-franz\u00f6sischen Beziehungen, Schul-Digitalisierung und Radverkehr in Saarbr\u00fccken - Cam\u00e4l\u00e9on\" \/>\n<meta property=\"og:description\" content=\"Der Oberb\u00fcrgermeister von Saarbr\u00fccken, Uwe Conradt, hat unserer Schule am 23. Mai einen Besuch abgestattet, um diese besser kennen zu lernen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.camaeleon.org\/en\/2022\/06\/12\/video-interview-mit-uwe-conradt-zu-deutsch-franzoesischen-beziehungen-schul-digitalisierung-und-radverkehr-in-saarbruecken\/\" \/>\n<meta property=\"og:site_name\" content=\"Cam\u00e4l\u00e9on\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/camaeleon.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-12T14:49:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-01T20:55:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.camaeleon.org\/wp-content\/uploads\/2022\/06\/Conradt2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Julian Bidot, Max Ernst, Ellenore Niederl\u00e4nder, Lili Carteron, Anouk Viero\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@camaeleonOrg\" \/>\n<meta name=\"twitter:site\" content=\"@camaeleonOrg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/2022\\\/06\\\/12\\\/video-interview-mit-uwe-conradt-zu-deutsch-franzoesischen-beziehungen-schul-digitalisierung-und-radverkehr-in-saarbruecken\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/2022\\\/06\\\/12\\\/video-interview-mit-uwe-conradt-zu-deutsch-franzoesischen-beziehungen-schul-digitalisierung-und-radverkehr-in-saarbruecken\\\/\"},\"author\":{\"name\":\"Julian Bidot\",\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/de\\\/#\\\/schema\\\/person\\\/4df212263ca8d70a0a60b3cdf9cb792e\"},\"headline\":\"Video-Interview mit Uwe Conradt zu deutsch-franz\u00f6sischen Beziehungen, Schul-Digitalisierung und Radverkehr in Saarbr\u00fccken\",\"datePublished\":\"2022-06-12T14:49:17+00:00\",\"dateModified\":\"2022-07-01T20:55:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/2022\\\/06\\\/12\\\/video-interview-mit-uwe-conradt-zu-deutsch-franzoesischen-beziehungen-schul-digitalisierung-und-radverkehr-in-saarbruecken\\\/\"},\"wordCount\":120,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/2022\\\/06\\\/12\\\/video-interview-mit-uwe-conradt-zu-deutsch-franzoesischen-beziehungen-schul-digitalisierung-und-radverkehr-in-saarbruecken\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.camaeleon.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Conradt2.jpg\",\"keywords\":[\"deutsch-franz\u00f6sische Beziehungen\",\"Deutsch-franz\u00f6sische Freundschaft\",\"Digitalisierung\",\"Oberb\u00fcrgermeister\",\"Radfahren\",\"Saarbr\u00fccken\",\"Uwe Conradt\"],\"articleSection\":[\"Politics\",\"Saarbr\u00fccken\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.camaeleon.org\\\/2022\\\/06\\\/12\\\/video-interview-mit-uwe-conradt-zu-deutsch-franzoesischen-beziehungen-schul-digitalisierung-und-radverkehr-in-saarbruecken\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/en\\\/2022\\\/06\\\/12\\\/video-interview-mit-uwe-conradt-zu-deutsch-franzoesischen-beziehungen-schul-digitalisierung-und-radverkehr-in-saarbruecken\\\/\",\"url\":\"https:\\\/\\\/www.camaeleon.org\\\/en\\\/2022\\\/06\\\/12\\\/video-interview-mit-uwe-conradt-zu-deutsch-franzoesischen-beziehungen-schul-digitalisierung-und-radverkehr-in-saarbruecken\\\/\",\"name\":\"Video-Interview mit Uwe Conradt zu deutsch-franz\u00f6sischen Beziehungen, Schul-Digitalisierung und Radverkehr in Saarbr\u00fccken - Cam\u00e4l\u00e9on\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/en\\\/2022\\\/06\\\/12\\\/video-interview-mit-uwe-conradt-zu-deutsch-franzoesischen-beziehungen-schul-digitalisierung-und-radverkehr-in-saarbruecken\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/2022\\\/06\\\/12\\\/video-interview-mit-uwe-conradt-zu-deutsch-franzoesischen-beziehungen-schul-digitalisierung-und-radverkehr-in-saarbruecken\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.camaeleon.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Conradt2.jpg\",\"datePublished\":\"2022-06-12T14:49:17+00:00\",\"dateModified\":\"2022-07-01T20:55:26+00:00\",\"description\":\"Der Oberb\u00fcrgermeister von Saarbr\u00fccken, Uwe Conradt, hat unserer Schule am 23. Mai einen Besuch abgestattet, um diese besser kennen zu lernen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/en\\\/2022\\\/06\\\/12\\\/video-interview-mit-uwe-conradt-zu-deutsch-franzoesischen-beziehungen-schul-digitalisierung-und-radverkehr-in-saarbruecken\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/www.camaeleon.org\\\/en\\\/2022\\\/06\\\/12\\\/video-interview-mit-uwe-conradt-zu-deutsch-franzoesischen-beziehungen-schul-digitalisierung-und-radverkehr-in-saarbruecken\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/en\\\/2022\\\/06\\\/12\\\/video-interview-mit-uwe-conradt-zu-deutsch-franzoesischen-beziehungen-schul-digitalisierung-und-radverkehr-in-saarbruecken\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.camaeleon.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Conradt2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.camaeleon.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Conradt2.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/en\\\/2022\\\/06\\\/12\\\/video-interview-mit-uwe-conradt-zu-deutsch-franzoesischen-beziehungen-schul-digitalisierung-und-radverkehr-in-saarbruecken\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.camaeleon.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Video-Interview mit Uwe Conradt zu deutsch-franz\u00f6sischen Beziehungen, Schul-Digitalisierung und Radverkehr in Saarbr\u00fccken\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.camaeleon.org\\\/en\\\/\",\"name\":\"Cam\u00e4l\u00e9on\",\"description\":\"The online student magazine by Deutsch-Franz\u00f6sisches Gymnasium Saarbr\u00fccken\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.camaeleon.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/en\\\/#organization\",\"name\":\"Cam\u00e4l\u00e9on\",\"url\":\"https:\\\/\\\/www.camaeleon.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.camaeleon.org\\\/wp-content\\\/uploads\\\/2011\\\/11\\\/CAM\u00c4LEON.jpg\",\"contentUrl\":\"https:\\\/\\\/www.camaeleon.org\\\/wp-content\\\/uploads\\\/2011\\\/11\\\/CAM\u00c4LEON.jpg\",\"width\":959,\"height\":959,\"caption\":\"Cam\u00e4l\u00e9on\"},\"image\":{\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/camaeleon.org\\\/\",\"https:\\\/\\\/x.com\\\/camaeleonOrg\",\"https:\\\/\\\/www.instagram.com\\\/camaeleon.dfg\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCl3TAUDdGuu_c7CD6ax6hYg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/de\\\/#\\\/schema\\\/person\\\/4df212263ca8d70a0a60b3cdf9cb792e\",\"name\":\"Julian Bidot\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/en\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/julian.jpgeeb77fb6f9ba90c8300a9123a3909722\",\"url\":\"https:\\\/\\\/www.camaeleon.org\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/julian.jpg\",\"contentUrl\":\"https:\\\/\\\/www.camaeleon.org\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/julian.jpg\",\"caption\":\"Julian Bidot\"},\"description\":\"Salut! Je m`appelle Julian. Voici quelques informations sur moi : - Depuis 2020 \u00e0 camaeleon.org - 18 ans - classe TL \u00c9crivez-moi des commentaires ou un mail! Amusez-vous bien sur cameleon.org !\",\"url\":\"https:\\\/\\\/www.camaeleon.org\\\/en\\\/author\\\/julian-bidot\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Video-Interview mit Uwe Conradt zu deutsch-franz\u00f6sischen Beziehungen, Schul-Digitalisierung und Radverkehr in Saarbr\u00fccken - Cam\u00e4l\u00e9on","description":"Der Oberb\u00fcrgermeister von Saarbr\u00fccken, Uwe Conradt, hat unserer Schule am 23. Mai einen Besuch abgestattet, um diese besser kennen zu lernen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.camaeleon.org\/en\/2022\/06\/12\/video-interview-mit-uwe-conradt-zu-deutsch-franzoesischen-beziehungen-schul-digitalisierung-und-radverkehr-in-saarbruecken\/","og_locale":"en_US","og_type":"article","og_title":"Video-Interview mit Uwe Conradt zu deutsch-franz\u00f6sischen Beziehungen, Schul-Digitalisierung und Radverkehr in Saarbr\u00fccken - Cam\u00e4l\u00e9on","og_description":"Der Oberb\u00fcrgermeister von Saarbr\u00fccken, Uwe Conradt, hat unserer Schule am 23. Mai einen Besuch abgestattet, um diese besser kennen zu lernen.","og_url":"https:\/\/www.camaeleon.org\/en\/2022\/06\/12\/video-interview-mit-uwe-conradt-zu-deutsch-franzoesischen-beziehungen-schul-digitalisierung-und-radverkehr-in-saarbruecken\/","og_site_name":"Cam\u00e4l\u00e9on","article_publisher":"https:\/\/www.facebook.com\/camaeleon.org\/","article_published_time":"2022-06-12T14:49:17+00:00","article_modified_time":"2022-07-01T20:55:26+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.camaeleon.org\/wp-content\/uploads\/2022\/06\/Conradt2.jpg","type":"image\/jpeg"}],"author":"Julian Bidot, Max Ernst, Ellenore Niederl\u00e4nder, Lili Carteron, Anouk Viero","twitter_card":"summary_large_image","twitter_creator":"@camaeleonOrg","twitter_site":"@camaeleonOrg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.camaeleon.org\/2022\/06\/12\/video-interview-mit-uwe-conradt-zu-deutsch-franzoesischen-beziehungen-schul-digitalisierung-und-radverkehr-in-saarbruecken\/#article","isPartOf":{"@id":"https:\/\/www.camaeleon.org\/2022\/06\/12\/video-interview-mit-uwe-conradt-zu-deutsch-franzoesischen-beziehungen-schul-digitalisierung-und-radverkehr-in-saarbruecken\/"},"author":{"name":"Julian Bidot","@id":"https:\/\/www.camaeleon.org\/de\/#\/schema\/person\/4df212263ca8d70a0a60b3cdf9cb792e"},"headline":"Video-Interview mit Uwe Conradt zu deutsch-franz\u00f6sischen Beziehungen, Schul-Digitalisierung und Radverkehr in Saarbr\u00fccken","datePublished":"2022-06-12T14:49:17+00:00","dateModified":"2022-07-01T20:55:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.camaeleon.org\/2022\/06\/12\/video-interview-mit-uwe-conradt-zu-deutsch-franzoesischen-beziehungen-schul-digitalisierung-und-radverkehr-in-saarbruecken\/"},"wordCount":120,"commentCount":0,"publisher":{"@id":"https:\/\/www.camaeleon.org\/de\/#organization"},"image":{"@id":"https:\/\/www.camaeleon.org\/2022\/06\/12\/video-interview-mit-uwe-conradt-zu-deutsch-franzoesischen-beziehungen-schul-digitalisierung-und-radverkehr-in-saarbruecken\/#primaryimage"},"thumbnailUrl":"https:\/\/www.camaeleon.org\/wp-content\/uploads\/2022\/06\/Conradt2.jpg","keywords":["deutsch-franz\u00f6sische Beziehungen","Deutsch-franz\u00f6sische Freundschaft","Digitalisierung","Oberb\u00fcrgermeister","Radfahren","Saarbr\u00fccken","Uwe Conradt"],"articleSection":["Politics","Saarbr\u00fccken"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.camaeleon.org\/2022\/06\/12\/video-interview-mit-uwe-conradt-zu-deutsch-franzoesischen-beziehungen-schul-digitalisierung-und-radverkehr-in-saarbruecken\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.camaeleon.org\/en\/2022\/06\/12\/video-interview-mit-uwe-conradt-zu-deutsch-franzoesischen-beziehungen-schul-digitalisierung-und-radverkehr-in-saarbruecken\/","url":"https:\/\/www.camaeleon.org\/en\/2022\/06\/12\/video-interview-mit-uwe-conradt-zu-deutsch-franzoesischen-beziehungen-schul-digitalisierung-und-radverkehr-in-saarbruecken\/","name":"Video-Interview mit Uwe Conradt zu deutsch-franz\u00f6sischen Beziehungen, Schul-Digitalisierung und Radverkehr in Saarbr\u00fccken - Cam\u00e4l\u00e9on","isPartOf":{"@id":"https:\/\/www.camaeleon.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.camaeleon.org\/en\/2022\/06\/12\/video-interview-mit-uwe-conradt-zu-deutsch-franzoesischen-beziehungen-schul-digitalisierung-und-radverkehr-in-saarbruecken\/#primaryimage"},"image":{"@id":"https:\/\/www.camaeleon.org\/2022\/06\/12\/video-interview-mit-uwe-conradt-zu-deutsch-franzoesischen-beziehungen-schul-digitalisierung-und-radverkehr-in-saarbruecken\/#primaryimage"},"thumbnailUrl":"https:\/\/www.camaeleon.org\/wp-content\/uploads\/2022\/06\/Conradt2.jpg","datePublished":"2022-06-12T14:49:17+00:00","dateModified":"2022-07-01T20:55:26+00:00","description":"Der Oberb\u00fcrgermeister von Saarbr\u00fccken, Uwe Conradt, hat unserer Schule am 23. Mai einen Besuch abgestattet, um diese besser kennen zu lernen.","breadcrumb":{"@id":"https:\/\/www.camaeleon.org\/en\/2022\/06\/12\/video-interview-mit-uwe-conradt-zu-deutsch-franzoesischen-beziehungen-schul-digitalisierung-und-radverkehr-in-saarbruecken\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/www.camaeleon.org\/en\/2022\/06\/12\/video-interview-mit-uwe-conradt-zu-deutsch-franzoesischen-beziehungen-schul-digitalisierung-und-radverkehr-in-saarbruecken\/"]]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.camaeleon.org\/en\/2022\/06\/12\/video-interview-mit-uwe-conradt-zu-deutsch-franzoesischen-beziehungen-schul-digitalisierung-und-radverkehr-in-saarbruecken\/#primaryimage","url":"https:\/\/www.camaeleon.org\/wp-content\/uploads\/2022\/06\/Conradt2.jpg","contentUrl":"https:\/\/www.camaeleon.org\/wp-content\/uploads\/2022\/06\/Conradt2.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.camaeleon.org\/en\/2022\/06\/12\/video-interview-mit-uwe-conradt-zu-deutsch-franzoesischen-beziehungen-schul-digitalisierung-und-radverkehr-in-saarbruecken\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.camaeleon.org\/en\/"},{"@type":"ListItem","position":2,"name":"Video-Interview mit Uwe Conradt zu deutsch-franz\u00f6sischen Beziehungen, Schul-Digitalisierung und Radverkehr in Saarbr\u00fccken"}]},{"@type":"WebSite","@id":"https:\/\/www.camaeleon.org\/en\/#website","url":"https:\/\/www.camaeleon.org\/en\/","name":"Cam\u00e4l\u00e9on","description":"The online student magazine by Deutsch-Franz\u00f6sisches Gymnasium Saarbr\u00fccken","publisher":{"@id":"https:\/\/www.camaeleon.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.camaeleon.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.camaeleon.org\/en\/#organization","name":"Cam\u00e4l\u00e9on","url":"https:\/\/www.camaeleon.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.camaeleon.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.camaeleon.org\/wp-content\/uploads\/2011\/11\/CAM\u00c4LEON.jpg","contentUrl":"https:\/\/www.camaeleon.org\/wp-content\/uploads\/2011\/11\/CAM\u00c4LEON.jpg","width":959,"height":959,"caption":"Cam\u00e4l\u00e9on"},"image":{"@id":"https:\/\/www.camaeleon.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/camaeleon.org\/","https:\/\/x.com\/camaeleonOrg","https:\/\/www.instagram.com\/camaeleon.dfg\/","https:\/\/www.youtube.com\/channel\/UCl3TAUDdGuu_c7CD6ax6hYg"]},{"@type":"Person","@id":"https:\/\/www.camaeleon.org\/de\/#\/schema\/person\/4df212263ca8d70a0a60b3cdf9cb792e","name":"Julian Bidot","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.camaeleon.org\/en\/wp-content\/uploads\/2020\/12\/julian.jpgeeb77fb6f9ba90c8300a9123a3909722","url":"https:\/\/www.camaeleon.org\/wp-content\/uploads\/2020\/12\/julian.jpg","contentUrl":"https:\/\/www.camaeleon.org\/wp-content\/uploads\/2020\/12\/julian.jpg","caption":"Julian Bidot"},"description":"Salut! Je m`appelle Julian. Voici quelques informations sur moi : - Depuis 2020 \u00e0 camaeleon.org - 18 ans - classe TL \u00c9crivez-moi des commentaires ou un mail! Amusez-vous bien sur cameleon.org !","url":"https:\/\/www.camaeleon.org\/en\/author\/julian-bidot\/"}]}},"_links":{"self":[{"href":"https:\/\/www.camaeleon.org\/en\/wp-json\/wp\/v2\/posts\/26569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.camaeleon.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.camaeleon.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.camaeleon.org\/en\/wp-json\/wp\/v2\/users\/143"}],"replies":[{"embeddable":true,"href":"https:\/\/www.camaeleon.org\/en\/wp-json\/wp\/v2\/comments?post=26569"}],"version-history":[{"count":0,"href":"https:\/\/www.camaeleon.org\/en\/wp-json\/wp\/v2\/posts\/26569\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.camaeleon.org\/en\/wp-json\/wp\/v2\/media\/26609"}],"wp:attachment":[{"href":"https:\/\/www.camaeleon.org\/en\/wp-json\/wp\/v2\/media?parent=26569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.camaeleon.org\/en\/wp-json\/wp\/v2\/categories?post=26569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.camaeleon.org\/en\/wp-json\/wp\/v2\/tags?post=26569"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.camaeleon.org\/en\/wp-json\/wp\/v2\/coauthors?post=26569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}