{"id":23847,"date":"2021-05-18T18:25:17","date_gmt":"2021-05-18T16:25:17","guid":{"rendered":"https:\/\/www.camaeleon.org\/?p=23847"},"modified":"2021-11-28T18:14:50","modified_gmt":"2021-11-28T17:14:50","slug":"le-mot-de-la-semaine-idahot2021","status":"publish","type":"post","link":"https:\/\/www.camaeleon.org\/de\/2021\/05\/18\/le-mot-de-la-semaine-idahot2021\/","title":{"rendered":"Le mot de la semaine : #IDAHOT2021"},"content":{"rendered":"<figure id=\"attachment_23849\" aria-describedby=\"caption-attachment-23849\" style=\"width: 300px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-23849\" src=\"https:\/\/www.camaeleon.org\/wp-content\/uploads\/2021\/05\/rainbow-flag-6216228_1920-300x210.jpg\" alt=\"Journ\u00e9e mondiale contre l'homophobie, la transphobie et la biphobie\" width=\"300\" height=\"210\" srcset=\"https:\/\/www.camaeleon.org\/wp-content\/uploads\/2021\/05\/rainbow-flag-6216228_1920-300x210.jpg 300w, https:\/\/www.camaeleon.org\/wp-content\/uploads\/2021\/05\/rainbow-flag-6216228_1920-855x600.jpg 855w, https:\/\/www.camaeleon.org\/wp-content\/uploads\/2021\/05\/rainbow-flag-6216228_1920-1536x1078.jpg 1536w, https:\/\/www.camaeleon.org\/wp-content\/uploads\/2021\/05\/rainbow-flag-6216228_1920-130x90.jpg 130w, https:\/\/www.camaeleon.org\/wp-content\/uploads\/2021\/05\/rainbow-flag-6216228_1920.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-23849\" class=\"wp-caption-text\">Photo : Trey_Musk \/ pixabay.com<\/figcaption><\/figure>\n<p>#IDAHOT2021, #17mai\u2026 Vous aurez peut-\u00eatre vu passer, lundi dernier, ces diff\u00e9rents hashtags sur les r\u00e9seaux sociaux. En effet, la journ\u00e9e mondiale contre l&#8217;homophobie, la transphobie et la biphobie a lieu chaque ann\u00e9e le 17 mai. Cette date fait r\u00e9f\u00e9rence au 17 mai 1990, journ\u00e9e o\u00f9 l\u2019homosexualit\u00e9 a \u00e9t\u00e9 officiellement reconnue comme n\u2019\u00e9tant pas une maladie mentale par l\u2019OMS (Organisation Mondiale de la Sant\u00e9). Quinze ans apr\u00e8s, en 2005, \u00e9tait cr\u00e9\u00e9 \u00ab l\u2019IDAHOT \u00bb, abr\u00e9viation de l\u2019anglais \u00ab International Day Against Homophobia, Transphobia &amp; biphobia \u00bb.<\/p>\n<p>Cette journ\u00e9e fait surtout parler d\u2019elle sur les r\u00e9seaux sociaux, puisque que la plus grosse part du combat se d\u00e9roule sur ces plateformes. Le but \u00e9tant d&#8217;informer et de mettre en\u00a0 lumi\u00e8re les minorit\u00e9s sexuelles et la transidentit\u00e9, Tweeter, Instagram et autres r\u00e9seaux sociaux deviennent des alli\u00e9s redoutables pour toucher un maximum de gens \u00e0 travers le monde.<\/p>\n<p>Cependant, malgr\u00e9 de remarquables progr\u00e8s ces derni\u00e8res ann\u00e9es, les mentalit\u00e9s restent inchang\u00e9es dans de nombreux pays o\u00f9 l\u2019homosexualit\u00e9 et la transidentit\u00e9 sont encore passibles d\u2019emprisonnement, voire pire, de la peine de mort. C\u2019est pourquoi chacun d\u2019entre nous peut avoir son r\u00f4le \u00e0 jouer, en s&#8217;informant et en informant les autres sur les droits des LGBT+ (personnes lesbiennes, gays, bisexuelles, transexuelles et autres orientations, caract\u00e9ristiques ou identit\u00e9s sexuelles), qui sont tout simplement les droits au respect et \u00e0 la dignit\u00e9 dus \u00e0 chaque \u00eatre humain.<\/p>\n<p>N&#8217;h\u00e9sitez pas \u00e0 relire <strong><a href=\"https:\/\/www.camaeleon.org\/de\/2018\/07\/02\/lgbt\/\" target=\"_blank\" rel=\"noopener noreferrer\">cet article<\/a><\/strong> sur l&#8217;homosexualit\u00e9 publi\u00e9 sur Cam\u00e4l\u00e9on en 2018.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>#IDAHOT2021, #17mai\u2026 Vous aurez peut-\u00eatre vu passer, lundi dernier, ces diff\u00e9rents hashtags sur les r\u00e9seaux sociaux. En effet, la journ\u00e9e mondiale contre l&#8217;homophobie, la transphobie<\/p>\n","protected":false},"author":144,"featured_media":23849,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[864,6],"tags":[1690,1687,1688,843,1692,1693,1694,1691,509,1689],"coauthors":[746],"class_list":["post-23847","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-le-mot-de-la-semaine","category-vie","tag-biphobie","tag-homophobie","tag-homosexualitaet","tag-homosexualite","tag-idahot","tag-journee-mondiale-contre-lhomophobie","tag-la-transphobie-et-la-biphobie","tag-lgbt","tag-schwul","tag-transphobie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le mot de la semaine : #IDAHOT2021 - Cam\u00e4l\u00e9on<\/title>\n<meta name=\"description\" content=\"En effet, la journ\u00e9e mondiale contre l&#039;homophobie, la transphobie et la biphobie a lieu chaque ann\u00e9e le 17 mai.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.camaeleon.org\/de\/2021\/05\/18\/le-mot-de-la-semaine-idahot2021\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le mot de la semaine : #IDAHOT2021 - Cam\u00e4l\u00e9on\" \/>\n<meta property=\"og:description\" content=\"En effet, la journ\u00e9e mondiale contre l&#039;homophobie, la transphobie et la biphobie a lieu chaque ann\u00e9e le 17 mai.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.camaeleon.org\/de\/2021\/05\/18\/le-mot-de-la-semaine-idahot2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Cam\u00e4l\u00e9on\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/camaeleon.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-18T16:25:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-28T17:14:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.camaeleon.org\/wp-content\/uploads\/2021\/05\/rainbow-flag-6216228_1920.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1347\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Clara Hoff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@camaeleonOrg\" \/>\n<meta name=\"twitter:site\" content=\"@camaeleonOrg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/2021\\\/05\\\/18\\\/le-mot-de-la-semaine-idahot2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/2021\\\/05\\\/18\\\/le-mot-de-la-semaine-idahot2021\\\/\"},\"author\":{\"name\":\"Clara Hoff\",\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/de\\\/#\\\/schema\\\/person\\\/5ca6f968356e20bf35e9dea8fd95dd06\"},\"headline\":\"Le mot de la semaine : #IDAHOT2021\",\"datePublished\":\"2021-05-18T16:25:17+00:00\",\"dateModified\":\"2021-11-28T17:14:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/2021\\\/05\\\/18\\\/le-mot-de-la-semaine-idahot2021\\\/\"},\"wordCount\":287,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/2021\\\/05\\\/18\\\/le-mot-de-la-semaine-idahot2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.camaeleon.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/rainbow-flag-6216228_1920.jpg\",\"keywords\":[\"biphobie\",\"homophobie\",\"Homosexualit\u00e4t\",\"homosexualit\u00e9\",\"IDAHOT\",\"journ\u00e9e mondiale contre l'homophobie\",\"la transphobie et la biphobie\",\"LGBT\",\"schwul\",\"transphobie\"],\"articleSection\":[\"Das Wort der Woche\",\"Leben\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.camaeleon.org\\\/2021\\\/05\\\/18\\\/le-mot-de-la-semaine-idahot2021\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/de\\\/2021\\\/05\\\/18\\\/le-mot-de-la-semaine-idahot2021\\\/\",\"url\":\"https:\\\/\\\/www.camaeleon.org\\\/de\\\/2021\\\/05\\\/18\\\/le-mot-de-la-semaine-idahot2021\\\/\",\"name\":\"Le mot de la semaine : #IDAHOT2021 - Cam\u00e4l\u00e9on\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/de\\\/2021\\\/05\\\/18\\\/le-mot-de-la-semaine-idahot2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/2021\\\/05\\\/18\\\/le-mot-de-la-semaine-idahot2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.camaeleon.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/rainbow-flag-6216228_1920.jpg\",\"datePublished\":\"2021-05-18T16:25:17+00:00\",\"dateModified\":\"2021-11-28T17:14:50+00:00\",\"description\":\"En effet, la journ\u00e9e mondiale contre l'homophobie, la transphobie et la biphobie a lieu chaque ann\u00e9e le 17 mai.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/de\\\/2021\\\/05\\\/18\\\/le-mot-de-la-semaine-idahot2021\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/www.camaeleon.org\\\/de\\\/2021\\\/05\\\/18\\\/le-mot-de-la-semaine-idahot2021\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/de\\\/2021\\\/05\\\/18\\\/le-mot-de-la-semaine-idahot2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.camaeleon.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/rainbow-flag-6216228_1920.jpg\",\"contentUrl\":\"https:\\\/\\\/www.camaeleon.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/rainbow-flag-6216228_1920.jpg\",\"width\":1920,\"height\":1347,\"caption\":\"Photo : Trey_Musk \\\/ pixabay.com\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/de\\\/2021\\\/05\\\/18\\\/le-mot-de-la-semaine-idahot2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.camaeleon.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le mot de la semaine : #IDAHOT2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.camaeleon.org\\\/de\\\/\",\"name\":\"Cam\u00e4l\u00e9on\",\"description\":\"Das Sch\u00fclermagazin des Deutsch-Franz\u00f6sischen Gymnasiums Saarbr\u00fccken\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.camaeleon.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/de\\\/#organization\",\"name\":\"Cam\u00e4l\u00e9on\",\"url\":\"https:\\\/\\\/www.camaeleon.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.camaeleon.org\\\/wp-content\\\/uploads\\\/2011\\\/11\\\/CAM\u00c4LEON.jpg\",\"contentUrl\":\"https:\\\/\\\/www.camaeleon.org\\\/wp-content\\\/uploads\\\/2011\\\/11\\\/CAM\u00c4LEON.jpg\",\"width\":959,\"height\":959,\"caption\":\"Cam\u00e4l\u00e9on\"},\"image\":{\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/camaeleon.org\\\/\",\"https:\\\/\\\/x.com\\\/camaeleonOrg\",\"https:\\\/\\\/www.instagram.com\\\/camaeleon.dfg\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCl3TAUDdGuu_c7CD6ax6hYg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/de\\\/#\\\/schema\\\/person\\\/5ca6f968356e20bf35e9dea8fd95dd06\",\"name\":\"Clara Hoff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.camaeleon.org\\\/de\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/clara.jpgbe2064d582ccc0a8eb13af3a323e8dd6\",\"url\":\"https:\\\/\\\/www.camaeleon.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/clara.jpg\",\"contentUrl\":\"https:\\\/\\\/www.camaeleon.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/clara.jpg\",\"caption\":\"Clara Hoff\"},\"url\":\"https:\\\/\\\/www.camaeleon.org\\\/de\\\/author\\\/clara-hoff\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le mot de la semaine : #IDAHOT2021 - Cam\u00e4l\u00e9on","description":"En effet, la journ\u00e9e mondiale contre l'homophobie, la transphobie et la biphobie a lieu chaque ann\u00e9e le 17 mai.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.camaeleon.org\/de\/2021\/05\/18\/le-mot-de-la-semaine-idahot2021\/","og_locale":"de_DE","og_type":"article","og_title":"Le mot de la semaine : #IDAHOT2021 - Cam\u00e4l\u00e9on","og_description":"En effet, la journ\u00e9e mondiale contre l'homophobie, la transphobie et la biphobie a lieu chaque ann\u00e9e le 17 mai.","og_url":"https:\/\/www.camaeleon.org\/de\/2021\/05\/18\/le-mot-de-la-semaine-idahot2021\/","og_site_name":"Cam\u00e4l\u00e9on","article_publisher":"https:\/\/www.facebook.com\/camaeleon.org\/","article_published_time":"2021-05-18T16:25:17+00:00","article_modified_time":"2021-11-28T17:14:50+00:00","og_image":[{"width":1920,"height":1347,"url":"https:\/\/www.camaeleon.org\/wp-content\/uploads\/2021\/05\/rainbow-flag-6216228_1920.jpg","type":"image\/jpeg"}],"author":"Clara Hoff","twitter_card":"summary_large_image","twitter_creator":"@camaeleonOrg","twitter_site":"@camaeleonOrg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.camaeleon.org\/2021\/05\/18\/le-mot-de-la-semaine-idahot2021\/#article","isPartOf":{"@id":"https:\/\/www.camaeleon.org\/2021\/05\/18\/le-mot-de-la-semaine-idahot2021\/"},"author":{"name":"Clara Hoff","@id":"https:\/\/www.camaeleon.org\/de\/#\/schema\/person\/5ca6f968356e20bf35e9dea8fd95dd06"},"headline":"Le mot de la semaine : #IDAHOT2021","datePublished":"2021-05-18T16:25:17+00:00","dateModified":"2021-11-28T17:14:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.camaeleon.org\/2021\/05\/18\/le-mot-de-la-semaine-idahot2021\/"},"wordCount":287,"commentCount":0,"publisher":{"@id":"https:\/\/www.camaeleon.org\/de\/#organization"},"image":{"@id":"https:\/\/www.camaeleon.org\/2021\/05\/18\/le-mot-de-la-semaine-idahot2021\/#primaryimage"},"thumbnailUrl":"https:\/\/www.camaeleon.org\/wp-content\/uploads\/2021\/05\/rainbow-flag-6216228_1920.jpg","keywords":["biphobie","homophobie","Homosexualit\u00e4t","homosexualit\u00e9","IDAHOT","journ\u00e9e mondiale contre l'homophobie","la transphobie et la biphobie","LGBT","schwul","transphobie"],"articleSection":["Das Wort der Woche","Leben"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.camaeleon.org\/2021\/05\/18\/le-mot-de-la-semaine-idahot2021\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.camaeleon.org\/de\/2021\/05\/18\/le-mot-de-la-semaine-idahot2021\/","url":"https:\/\/www.camaeleon.org\/de\/2021\/05\/18\/le-mot-de-la-semaine-idahot2021\/","name":"Le mot de la semaine : #IDAHOT2021 - Cam\u00e4l\u00e9on","isPartOf":{"@id":"https:\/\/www.camaeleon.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.camaeleon.org\/de\/2021\/05\/18\/le-mot-de-la-semaine-idahot2021\/#primaryimage"},"image":{"@id":"https:\/\/www.camaeleon.org\/2021\/05\/18\/le-mot-de-la-semaine-idahot2021\/#primaryimage"},"thumbnailUrl":"https:\/\/www.camaeleon.org\/wp-content\/uploads\/2021\/05\/rainbow-flag-6216228_1920.jpg","datePublished":"2021-05-18T16:25:17+00:00","dateModified":"2021-11-28T17:14:50+00:00","description":"En effet, la journ\u00e9e mondiale contre l'homophobie, la transphobie et la biphobie a lieu chaque ann\u00e9e le 17 mai.","breadcrumb":{"@id":"https:\/\/www.camaeleon.org\/de\/2021\/05\/18\/le-mot-de-la-semaine-idahot2021\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/www.camaeleon.org\/de\/2021\/05\/18\/le-mot-de-la-semaine-idahot2021\/"]]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.camaeleon.org\/de\/2021\/05\/18\/le-mot-de-la-semaine-idahot2021\/#primaryimage","url":"https:\/\/www.camaeleon.org\/wp-content\/uploads\/2021\/05\/rainbow-flag-6216228_1920.jpg","contentUrl":"https:\/\/www.camaeleon.org\/wp-content\/uploads\/2021\/05\/rainbow-flag-6216228_1920.jpg","width":1920,"height":1347,"caption":"Photo : Trey_Musk \/ pixabay.com"},{"@type":"BreadcrumbList","@id":"https:\/\/www.camaeleon.org\/de\/2021\/05\/18\/le-mot-de-la-semaine-idahot2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.camaeleon.org\/de\/"},{"@type":"ListItem","position":2,"name":"Le mot de la semaine : #IDAHOT2021"}]},{"@type":"WebSite","@id":"https:\/\/www.camaeleon.org\/de\/#website","url":"https:\/\/www.camaeleon.org\/de\/","name":"Cam\u00e4l\u00e9on","description":"Das Sch\u00fclermagazin des Deutsch-Franz\u00f6sischen Gymnasiums Saarbr\u00fccken","publisher":{"@id":"https:\/\/www.camaeleon.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.camaeleon.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.camaeleon.org\/de\/#organization","name":"Cam\u00e4l\u00e9on","url":"https:\/\/www.camaeleon.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.camaeleon.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.camaeleon.org\/wp-content\/uploads\/2011\/11\/CAM\u00c4LEON.jpg","contentUrl":"https:\/\/www.camaeleon.org\/wp-content\/uploads\/2011\/11\/CAM\u00c4LEON.jpg","width":959,"height":959,"caption":"Cam\u00e4l\u00e9on"},"image":{"@id":"https:\/\/www.camaeleon.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/camaeleon.org\/","https:\/\/x.com\/camaeleonOrg","https:\/\/www.instagram.com\/camaeleon.dfg\/","https:\/\/www.youtube.com\/channel\/UCl3TAUDdGuu_c7CD6ax6hYg"]},{"@type":"Person","@id":"https:\/\/www.camaeleon.org\/de\/#\/schema\/person\/5ca6f968356e20bf35e9dea8fd95dd06","name":"Clara Hoff","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.camaeleon.org\/de\/wp-content\/uploads\/2020\/11\/clara.jpgbe2064d582ccc0a8eb13af3a323e8dd6","url":"https:\/\/www.camaeleon.org\/wp-content\/uploads\/2020\/11\/clara.jpg","contentUrl":"https:\/\/www.camaeleon.org\/wp-content\/uploads\/2020\/11\/clara.jpg","caption":"Clara Hoff"},"url":"https:\/\/www.camaeleon.org\/de\/author\/clara-hoff\/"}]}},"_links":{"self":[{"href":"https:\/\/www.camaeleon.org\/de\/wp-json\/wp\/v2\/posts\/23847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.camaeleon.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.camaeleon.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.camaeleon.org\/de\/wp-json\/wp\/v2\/users\/144"}],"replies":[{"embeddable":true,"href":"https:\/\/www.camaeleon.org\/de\/wp-json\/wp\/v2\/comments?post=23847"}],"version-history":[{"count":0,"href":"https:\/\/www.camaeleon.org\/de\/wp-json\/wp\/v2\/posts\/23847\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.camaeleon.org\/de\/wp-json\/wp\/v2\/media\/23849"}],"wp:attachment":[{"href":"https:\/\/www.camaeleon.org\/de\/wp-json\/wp\/v2\/media?parent=23847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.camaeleon.org\/de\/wp-json\/wp\/v2\/categories?post=23847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.camaeleon.org\/de\/wp-json\/wp\/v2\/tags?post=23847"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.camaeleon.org\/de\/wp-json\/wp\/v2\/coauthors?post=23847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}